{"id":43285,"date":"2021-09-01T14:12:31","date_gmt":"2021-09-01T14:12:31","guid":{"rendered":"https:\/\/joyn.eu\/wat-is-edenred\/"},"modified":"2021-09-14T18:11:20","modified_gmt":"2021-09-14T18:11:20","slug":"quest-ce-quedenred","status":"publish","type":"post","link":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/","title":{"rendered":"Qu\u2019est-ce qu\u2019Edenred ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43285\" class=\"elementor elementor-43285 elementor-41324\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b2a3f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b2a3f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18c4bbc\" data-id=\"18c4bbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8857bf3 elementor-widget elementor-widget-text-editor\" data-id=\"8857bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs en Belgique.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:7041,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:[null,2,0],&quot;15&quot;:&quot;Arial&quot;}\">Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs en Belgique.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs en Belgique.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[255,254],"tags":[],"class_list":["post-43285","post","type-post","status-publish","format-standard","hentry","category-edenred-fr-be","category-paiement-mobile-avec-joyn"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u2019est-ce qu\u2019Edenred ? - Joyn<\/title>\n<meta name=\"description\" content=\"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u2019est-ce qu\u2019Edenred ? - Joyn\" \/>\n<meta property=\"og:description\" content=\"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/\" \/>\n<meta property=\"og:site_name\" content=\"Joyn\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T14:12:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-14T18:11:20+00:00\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#\\\/schema\\\/person\\\/294d91a999da7cbd9d19f85a00ce41b6\"},\"headline\":\"Qu\u2019est-ce qu\u2019Edenred ?\",\"datePublished\":\"2021-09-01T14:12:31+00:00\",\"dateModified\":\"2021-09-14T18:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/\"},\"wordCount\":32,\"publisher\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#organization\"},\"articleSection\":[\"Edenred\",\"Paiement mobile avec Joyn\"],\"inLanguage\":\"fr-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/\",\"url\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/\",\"name\":\"Qu\u2019est-ce qu\u2019Edenred ? - Joyn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#website\"},\"datePublished\":\"2021-09-01T14:12:31+00:00\",\"dateModified\":\"2021-09-14T18:11:20+00:00\",\"description\":\"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/quest-ce-quedenred\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/home-merchant-new-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u2019est-ce qu\u2019Edenred ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/\",\"name\":\"Joyn\",\"description\":\"Quand vos clients deviennent des fans\",\"publisher\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#organization\",\"name\":\"Joyn\",\"url\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/joyn.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Blue-green-h40.png\",\"contentUrl\":\"https:\\\/\\\/joyn.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Blue-green-h40.png\",\"width\":83,\"height\":40,\"caption\":\"Joyn\"},\"image\":{\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/#\\\/schema\\\/person\\\/294d91a999da7cbd9d19f85a00ce41b6\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"sameAs\":[\"http:\\\/\\\/joyn.eu\"],\"url\":\"https:\\\/\\\/joyn.eu\\\/fr-be\\\/author\\\/joyn-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u2019est-ce qu\u2019Edenred ? - Joyn","description":"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu\u2019est-ce qu\u2019Edenred ? - Joyn","og_description":"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs","og_url":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/","og_site_name":"Joyn","article_published_time":"2021-09-01T14:12:31+00:00","article_modified_time":"2021-09-14T18:11:20+00:00","author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/#article","isPartOf":{"@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/"},"author":{"name":"Admin","@id":"https:\/\/joyn.eu\/fr-be\/#\/schema\/person\/294d91a999da7cbd9d19f85a00ce41b6"},"headline":"Qu\u2019est-ce qu\u2019Edenred ?","datePublished":"2021-09-01T14:12:31+00:00","dateModified":"2021-09-14T18:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/"},"wordCount":32,"publisher":{"@id":"https:\/\/joyn.eu\/fr-be\/#organization"},"articleSection":["Edenred","Paiement mobile avec Joyn"],"inLanguage":"fr-BE"},{"@type":"WebPage","@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/","url":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/","name":"Qu\u2019est-ce qu\u2019Edenred ? - Joyn","isPartOf":{"@id":"https:\/\/joyn.eu\/fr-be\/#website"},"datePublished":"2021-09-01T14:12:31+00:00","dateModified":"2021-09-14T18:11:20+00:00","description":"Edenred est le leader du march\u00e9 en mati\u00e8re de ch\u00e8ques-repas, \u00e9co-ch\u00e8ques et ch\u00e8ques-cadeaux num\u00e9riques et compte plus de 1,5 million d\u2019utilisateurs","breadcrumb":{"@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joyn.eu\/fr-be\/quest-ce-quedenred\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/joyn.eu\/fr-be\/home-merchant-new-fr\/"},{"@type":"ListItem","position":2,"name":"Qu\u2019est-ce qu\u2019Edenred ?"}]},{"@type":"WebSite","@id":"https:\/\/joyn.eu\/fr-be\/#website","url":"https:\/\/joyn.eu\/fr-be\/","name":"Joyn","description":"Quand vos clients deviennent des fans","publisher":{"@id":"https:\/\/joyn.eu\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joyn.eu\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/joyn.eu\/fr-be\/#organization","name":"Joyn","url":"https:\/\/joyn.eu\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/joyn.eu\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/joyn.eu\/wp-content\/uploads\/2021\/02\/Blue-green-h40.png","contentUrl":"https:\/\/joyn.eu\/wp-content\/uploads\/2021\/02\/Blue-green-h40.png","width":83,"height":40,"caption":"Joyn"},"image":{"@id":"https:\/\/joyn.eu\/fr-be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/joyn.eu\/fr-be\/#\/schema\/person\/294d91a999da7cbd9d19f85a00ce41b6","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/secure.gravatar.com\/avatar\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fb8363e7935397a84f2b3c011afdb30728d512983412e10b7ac47a1260dcc87?s=96&d=mm&r=g","caption":"Admin"},"sameAs":["http:\/\/joyn.eu"],"url":"https:\/\/joyn.eu\/fr-be\/author\/joyn-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/posts\/43285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/comments?post=43285"}],"version-history":[{"count":4,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/posts\/43285\/revisions"}],"predecessor-version":[{"id":43294,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/posts\/43285\/revisions\/43294"}],"wp:attachment":[{"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=43285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/categories?post=43285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joyn.eu\/fr-be\/wp-json\/wp\/v2\/tags?post=43285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}